{"id":2226,"date":"2026-09-02T11:43:56","date_gmt":"2026-09-02T09:43:56","guid":{"rendered":"https:\/\/www.rachida-dati.eu\/actualites\/deux-morts-dans-une-collision-entre-un-bateau-et-une-embarcation-gonflable-au-large-des-cotes-mediterraneennes-francaises\/"},"modified":"2026-09-02T11:43:58","modified_gmt":"2026-09-02T09:43:58","slug":"deux-morts-dans-une-collision-entre-un-bateau-et-une-embarcation-gonflable-au-large-des-cotes-mediterraneennes-francaises","status":"publish","type":"post","link":"https:\/\/www.rachida-dati.eu\/actualites\/deux-morts-dans-une-collision-entre-un-bateau-et-une-embarcation-gonflable-au-large-des-cotes-mediterraneennes-francaises\/","title":{"rendered":"Deux morts dans une collision entre un bateau et une embarcation gonflable au large des c\u00f4tes m\u00e9diterran\u00e9ennes fran\u00e7aises"},"content":{"rendered":"<div data-element-guid=\"7f7332a5-aca0-4fee-9990-ec700b171346\">\n<p class=\"subtitle \" style=\"\">Le pilote aurait chut\u00e9 par-dessus bord et dans l&rsquo;h\u00e9lice du bateau avant que l&#8217;embarcation ne fasse des tours et ne percute l&#8217;embarcation gonflable qu&rsquo;il tractait<\/p>\n<\/p>\n<\/div>\n<div data-element-guid=\"ce6378e9-99fe-4aa3-91b1-0761b0446386\">\n<p><!-- placeholder(#1) --><\/p>\n<p>Deux personnes sont mortes et cinq autres ont \u00e9t\u00e9 bless\u00e9es \u2013 dont une est dans un \u00e9tat critique \u2013 \u00e0 la suite d&rsquo;un accident maritime insolite dans le sud de la France, hier.<\/p>\n<p>L&rsquo;incident a eu lieu au large des c\u00f4tes pr\u00e8s de Saint-Cyprien (Pyr\u00e9n\u00e9es-Orientales) mardi (1er septembre) apr\u00e8s une collision entre un bateau motoris\u00e9 et l&#8217;embarcation gonflable qu&rsquo;il tractait.<\/p>\n<p>Le pilote du bateau et l&rsquo;une des personnes sur l&#8217;embarcation gonflable sont morts, tandis que plusieurs autres \u00ab passagers \u00bb ont \u00e9t\u00e9 bless\u00e9s.<\/p>\n<p>Une enqu\u00eate pr\u00e9liminaire pour homicide involontaire a \u00e9t\u00e9 ouverte par le parquet local, mais cela peut \u00e9voluer \u00e0 mesure que de nouveaux \u00e9l\u00e9ments sont r\u00e9v\u00e9l\u00e9s.\u00a0<\/p>\n<h2>Incident choquant<\/h2>\n<p>\u00ab Il semble que le bateau ait \u00e9t\u00e9 destabilis\u00e9 par les vagues qu&rsquo;il cr\u00e9ait [alors qu&rsquo;il transportait les passagers] et que le pilote ait \u00e9t\u00e9 \u00e9ject\u00e9 \u00bb, a d\u00e9clar\u00e9 le procureur de Perpignan J\u00e9r\u00f4me Bourrier \u00e0 l&rsquo;AFP.<\/p>\n<p>\u00ab Le bateau aurait perdu le contr\u00f4le, faisant des tours sur lui-m\u00eame, roulant sur l&#8217;embarcation gonflable tract\u00e9e et heurtant les victimes \u00bb, a ajout\u00e9 M. Bourrier, bien qu&rsquo;il ait soulign\u00e9 que les d\u00e9tails de l&rsquo;incident restaient \u00e0 \u00eatre examin\u00e9s et que les premiers r\u00e9cits de ce qui s&rsquo;est pass\u00e9 devaient \u00eatre trait\u00e9s avec prudence.\u00a0<\/p>\n<p>\u00ab Le pilote a \u00e9t\u00e9 frapp\u00e9 par l&rsquo;h\u00e9lice du bateau et a sombr\u00e9 imm\u00e9diatement \u00bb, a d\u00e9clar\u00e9 un t\u00e9moin de l&rsquo;incident, cit\u00e9 par le m\u00e9dia Le Figaro.\u00a0<\/p>\n<p>Le corps du pilote a ensuite \u00e9t\u00e9 rep\u00each\u00e9 des eaux par les services d&rsquo;urgence.<\/p>\n<p>\u00ab Le bateau sans \u00e9quipage a poursuivi son virage et a heurt\u00e9 l&#8217;embarcation gonflable qu&rsquo;il tractait, tuant une femme et blessant gravement un homme au bras et \u00e0 la jambe. \u00bb<\/p>\n<p>On ignore ce qui a pouss\u00e9 le pilote \u00e0 tomber par-dessus bord, mais les m\u00e9dias locaux \u00e9voquent que cela s&rsquo;est produit lorsque le bateau effectuait un virage large.\u00a0<\/p>\n<p>D&rsquo;autres rapports des m\u00e9dias sugg\u00e8rent que le pilote n&rsquo;avait pas correctement accroch\u00e9 le \u00ab kill-switch \u00bb \u00e0 sa personne, ce qui permet d&rsquo;arr\u00eater le moteur du bateau en cas d&rsquo;incident.\u00a0<\/p>\n<h2>Les r\u00e8gles ont-elles \u00e9t\u00e9 respect\u00e9es ?<\/h2>\n<p>Une partie de l&rsquo;enqu\u00eate examinera sans doute si le bateau \u00e9tait correctement \u00e9quip\u00e9 pour le remorquage des passagers.\u00a0<\/p>\n<p>Les sports nautiques sont une activit\u00e9 populaire le long du littoral m\u00e9diterran\u00e9en, y compris l&rsquo;utilisation d&#8217;embarcations gonflables tract\u00e9es ou d&rsquo;appareils li\u00e9s aux bateaux, mais des r\u00e8gles strictes doivent \u00eatre respect\u00e9es.<\/p>\n<p>Celles-ci s&rsquo;appliquent aussi bien aux entreprises proposant des activit\u00e9s qu&rsquo;aux embarcations priv\u00e9es.<\/p>\n<p>Les r\u00e8gles principales, soulign\u00e9es par l&rsquo;avocat Bertrand Coste pour le site nautique superyachtnews, comprennent :\u00a0<\/p>\n<ul>\n<li>\n<p>Les activit\u00e9s de remorquage ne peuvent \u00eatre r\u00e9alis\u00e9es que pendant la journ\u00e9e<\/p>\n<\/li>\n<li>\n<p>Les bateaux doivent emprunter des canaux de navigation autoris\u00e9s lors de leur d\u00e9part ou de leur retour sur le littoral<\/p>\n<\/li>\n<li>\n<p>Toutes les personnes sur l&#8217;embarcation gonflable doivent porter un \u00e9quipement de s\u00e9curit\u00e9 ad\u00e9quat (un dispositif de flottabilit\u00e9 en cas de chute par-dessus bord)<\/p>\n<\/li>\n<li>\n<p>La corde de remorquage doit \u00eatre de couleur vive et facilement identifiable.<\/p>\n<\/li>\n<li>\n<p>Le v\u00e9hicule de remorquage doit \u00eatre \u00e9quip\u00e9 d&rsquo;un syst\u00e8me de lib\u00e9ration rapide de la ligne de remorquage, ainsi que d&rsquo;un drapeau orange pour une meilleure visibilit\u00e9<\/p>\n<\/li>\n<li>\n<p>Il doit y avoir au moins deux personnes \u00e0 bord du bateau \u2013 l&rsquo;une pour piloter le v\u00e9hicule, l&rsquo;autre, \u00e2g\u00e9e d&rsquo;au moins 16 ans, pour \u00eatre en charge des personnes sur l&#8217;embarcation gonflable tract\u00e9e<\/p>\n<\/li>\n<li>\n<p>Le bateau doit pouvoir accueillir toutes les personnes sur l&#8217;embarcation gonflable en plus de celles d\u00e9j\u00e0 \u00e0 bord, en cas d&rsquo;incident\u00a0<\/p>\n<\/li>\n<\/ul>\n<p>Les r\u00e8gles compl\u00e8tes peuvent \u00eatre consult\u00e9es via les diverses <span class=\"font-weight-bold m-font-weight-bold \" data-lab-font_weight=\"font-weight-bold\">ordonnances pr\u00e9fectorales<\/span> \u00e9mises par les autorit\u00e9s maritimes de la M\u00e9diterran\u00e9e.<\/p>\n<p>Notez que des r\u00e8gles diff\u00e9rentes s&rsquo;appliquent aux navires le long des c\u00f4tes atlantiques et septentrionales, ainsi que sur les voies navigables.<\/p>\n<p>Il est pr\u00e9f\u00e9rable de v\u00e9rifier les ordonnances pr\u00e9fectorales locales avant d&rsquo;utiliser votre bateau pour tout remorquage sur les eaux fran\u00e7aises.<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Le pilote aurait chut\u00e9 par-dessus bord et dans l&rsquo;h\u00e9lice du bateau avant que l&#8217;embarcation ne fasse des tours et ne percute l&#8217;embarcation gonflable qu&rsquo;il tractait Deux personnes sont mortes et cinq autres ont \u00e9t\u00e9 bless\u00e9es \u2013 dont une est dans un \u00e9tat critique \u2013 \u00e0 la suite d&rsquo;un accident maritime insolite dans le sud de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":2227,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-2226","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-non-classe"],"_links":{"self":[{"href":"https:\/\/www.rachida-dati.eu\/actualites\/wp-json\/wp\/v2\/posts\/2226","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rachida-dati.eu\/actualites\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rachida-dati.eu\/actualites\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rachida-dati.eu\/actualites\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rachida-dati.eu\/actualites\/wp-json\/wp\/v2\/comments?post=2226"}],"version-history":[{"count":1,"href":"https:\/\/www.rachida-dati.eu\/actualites\/wp-json\/wp\/v2\/posts\/2226\/revisions"}],"predecessor-version":[{"id":2228,"href":"https:\/\/www.rachida-dati.eu\/actualites\/wp-json\/wp\/v2\/posts\/2226\/revisions\/2228"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rachida-dati.eu\/actualites\/wp-json\/wp\/v2\/media\/2227"}],"wp:attachment":[{"href":"https:\/\/www.rachida-dati.eu\/actualites\/wp-json\/wp\/v2\/media?parent=2226"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rachida-dati.eu\/actualites\/wp-json\/wp\/v2\/categories?post=2226"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rachida-dati.eu\/actualites\/wp-json\/wp\/v2\/tags?post=2226"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}